{"id":16580,"date":"2024-06-05T16:38:21","date_gmt":"2024-06-05T19:38:21","guid":{"rendered":"https:\/\/rotario.com.br\/site\/?p=16580"},"modified":"2024-06-05T16:38:23","modified_gmt":"2024-06-05T19:38:23","slug":"abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco","status":"publish","type":"post","link":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/","title":{"rendered":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco"},"content":{"rendered":"\n<p>A abertura do Junho Verde aconteceu na manh\u00e3 desta quarta-feira (5), no Dia Mundial do Meio Ambiente, na Pra\u00e7a do Bar do Coco. O evento foi organizado pela Secretaria de Ambiente e Sustentabilidade, Secretaria de Educa\u00e7\u00e3o e Guarda Municipal e contou com a parceria do Nupem\/ UFRJ, BRK, Marlin Azul, entre outras empresas privadas.<br><\/p>\n\n\n\n<p>O evento contou com a presen\u00e7a do vice-prefeito, C\u00e9lio Chapeta, que ressaltou a import\u00e2ncia da data para que a sociedade fique atenta para preservar o meio ambiente do munic\u00edpio.<br><br>A secret\u00e1ria de Ambiente e Sustentabilidade, Isaura Sales, ressaltou a import\u00e2ncia de comemorar o Dia do Meio Ambiente \u201c Nossa Maca\u00e9 \u00e9 rica em biodiversidade. Come\u00e7amos cuidando do nosso meio ambiente a partir da nossa casa. Precisamos Conhecer para preservar&#8221;<br><br>Ressaltou ainda a import\u00e2ncia da parceria com o Nupem nas a\u00e7\u00f5es de educa\u00e7\u00e3o ambiental na cidade.<br><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cA parceria com a comunidade acad\u00eamica, em especial com o NUPEM, tem sido primordial nas a\u00e7\u00f5es de EA e nos projetos que ser\u00e3o realizados na cidade baseados em solu\u00e7\u00f5es na preserva\u00e7\u00e3o da natureza\u201d, contou.<\/p>\n<\/blockquote>\n\n\n\n<p>A abertura do evento contou tamb\u00e9m com a participa\u00e7\u00e3o da Corpora\u00e7\u00e3o Musical Elza Ibrhaim e ainda de 200 estudantes da rede municipal de ensino que puderam ver de perto muitos projetos que funcionam no munic\u00edpio.<\/p>\n\n\n\n<p><strong>Projetos<br><\/strong>Entre os projetos que puderam ser conhecidos foi o de \u201cTartarugas e Insetos\u201d, do Nupem. A pesquisa foi organizada pelo professor Vin\u00edcius Albano.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u201cEsse trabalho contou com alunos de gradua\u00e7\u00e3o de Biologia e o objetivo dele \u00e9 mostrar a import\u00e2ncia dos insetos na vida das pessoas, como na agricultura, economia, sa\u00fade p\u00fablica e ainda insetos espec\u00edficos da cidade de Maca\u00e9 e da regi\u00e3o urbana\u201d, explicou.<\/p>\n<\/blockquote>\n\n\n\n<p>Outros projetos tamb\u00e9m participaram da exposi\u00e7\u00e3o como o \u201cMar\u00e9 Limpa: Pesquisas para redu\u00e7\u00e3o do lixo do oceano\u201d, desenvolvido pela UFRJ sob coordena\u00e7\u00e3o da Professora Paula Dibiase e o projeto \u201cCi\u00eancias em Sana\u201d do professor Maur\u00edcio Molisane al\u00e9m da \u201cTrilhas na Restinga \u201d, organizada pelo professor Rodrigo Lemes, para conhecer o Parque do Barreto, al\u00e9m dos trabalhos que s\u00e3o desenvolvidos pela Guarda Ambiental e Cevas.<\/p>\n\n\n\n<p>A programa\u00e7\u00e3o do Junho Verde ser\u00e1 realizada at\u00e9 o dia 26 deste m\u00eas.<\/p>\n\n\n\n<p><strong>Programa\u00e7\u00e3o:<br><\/strong><strong><br><br>06\/06 \u2013 9h-&nbsp;<\/strong>Replantio do Pomar Urbano de Imboassica &#8211; Ser\u00e3o realizados replantios de esp\u00e9cies frut\u00edferas como acerola, amora e n\u00easpera.<\/p>\n\n\n\n<p><strong>11\/06 \u2013 9h-&nbsp;<\/strong>Trilha da ci\u00eancia no Nupem &#8211; Na trilha da ci\u00eancia do Nupem, a natureza ganha vida com o plantio de mudas nativas da Mata Atl\u00e2ntica.<\/p>\n\n\n\n<p><strong>11\/06 \u2013 13h30-&nbsp;<\/strong>Oficina de Integra\u00e7\u00e3o do Plano de Manejo do Parque Natural Municipal do Arquip\u00e9lago de Santana e da Restinga do Barreto, no audit\u00f3rio do Nupem.<\/p>\n\n\n\n<p><strong>15\/06 \u2013 9h-&nbsp;<\/strong>Atividade com os Escoteiros dos Grupos de Maca\u00e9 e Rio das Ostras, com o tema \u201cSempre alerta para a fiscaliza\u00e7\u00e3o ambiental\u201d , no Bosque da Lagoa de Imboassica.<\/p>\n\n\n\n<p><strong>19\/06 \u2013 9h-&nbsp;<\/strong>Apresenta\u00e7\u00e3o do projeto \u201cSensitrilha\u201d com alunos da educa\u00e7\u00e3o inclusiva no Parque Atalaia<\/p>\n\n\n\n<p><strong>19\/06 \u2013 8h-&nbsp;<\/strong>Limpeza Ilha do Franc\u00eas<\/p>\n\n\n\n<p><strong>26\/06 \u2013 9h-&nbsp;<\/strong>Lagoa de Imboassica &#8211; 3\u00aa etapa do projeto \u201cResgatando o passado e semeando o futuro\u201d com alunos do col\u00e9gio Municipal Renato Martins, Projeto \u201cCanoa na Lagoa\u201d e a\u00e7\u00e3o de limpeza na margem da Lagoa<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A abertura do Junho Verde aconteceu na manh\u00e3 desta quarta-feira (5), no Dia Mundial do Meio Ambiente, na Pra\u00e7a do Bar do Coco. O evento foi organizado pela Secretaria de Ambiente e Sustentabilidade, Secretaria de Educa\u00e7\u00e3o e Guarda Municipal e contou com a parceria do Nupem\/ UFRJ, BRK, Marlin Azul, entre outras empresas privadas. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16581,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[225,52,119],"tags":[],"class_list":["post-16580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-macae","category-macae-costa-do-sol"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio\" \/>\n<meta property=\"og:description\" content=\"A abertura do Junho Verde aconteceu na manh\u00e3 desta quarta-feira (5), no Dia Mundial do Meio Ambiente, na Pra\u00e7a do Bar do Coco. O evento foi organizado pela Secretaria de Ambiente e Sustentabilidade, Secretaria de Educa\u00e7\u00e3o e Guarda Municipal e contou com a parceria do Nupem\/ UFRJ, BRK, Marlin Azul, entre outras empresas privadas. O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\" \/>\n<meta property=\"og:site_name\" content=\"Rota Rio\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T19:38:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-05T19:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2126\" \/>\n\t<meta property=\"og:image:height\" content=\"1417\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Galv\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Galv\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\"},\"author\":{\"name\":\"Galv\u00e3o\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7\"},\"headline\":\"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco\",\"datePublished\":\"2024-06-05T19:38:21+00:00\",\"dateModified\":\"2024-06-05T19:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg\",\"articleSection\":[\"Destaque\",\"Maca\u00e9\",\"Maca\u00e9\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\",\"url\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\",\"name\":\"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio\",\"isPartOf\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg\",\"datePublished\":\"2024-06-05T19:38:21+00:00\",\"dateModified\":\"2024-06-05T19:38:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage\",\"url\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg\",\"contentUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg\",\"width\":2126,\"height\":1417},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/rotario.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rotario.com.br\/site\/#website\",\"url\":\"https:\/\/rotario.com.br\/site\/\",\"name\":\"Rota Rio\",\"description\":\"Aqui, o Rio de Janeiro \u00e9 a pauta!\",\"publisher\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rotario.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\",\"name\":\"Rota Rio\",\"url\":\"https:\/\/rotario.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png\",\"contentUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png\",\"width\":2048,\"height\":654,\"caption\":\"Rota Rio\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7\",\"name\":\"Galv\u00e3o\",\"url\":\"https:\/\/rotario.com.br\/site\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/","og_locale":"pt_BR","og_type":"article","og_title":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio","og_description":"A abertura do Junho Verde aconteceu na manh\u00e3 desta quarta-feira (5), no Dia Mundial do Meio Ambiente, na Pra\u00e7a do Bar do Coco. O evento foi organizado pela Secretaria de Ambiente e Sustentabilidade, Secretaria de Educa\u00e7\u00e3o e Guarda Municipal e contou com a parceria do Nupem\/ UFRJ, BRK, Marlin Azul, entre outras empresas privadas. O [&hellip;]","og_url":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/","og_site_name":"Rota Rio","article_published_time":"2024-06-05T19:38:21+00:00","article_modified_time":"2024-06-05T19:38:23+00:00","og_image":[{"width":2126,"height":1417,"url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg","type":"image\/jpeg"}],"author":"Galv\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Galv\u00e3o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#article","isPartOf":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/"},"author":{"name":"Galv\u00e3o","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7"},"headline":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco","datePublished":"2024-06-05T19:38:21+00:00","dateModified":"2024-06-05T19:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/rotario.com.br\/site\/#organization"},"image":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage"},"thumbnailUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg","articleSection":["Destaque","Maca\u00e9","Maca\u00e9"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/","url":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/","name":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco - Rota Rio","isPartOf":{"@id":"https:\/\/rotario.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage"},"image":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage"},"thumbnailUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg","datePublished":"2024-06-05T19:38:21+00:00","dateModified":"2024-06-05T19:38:23+00:00","breadcrumb":{"@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#primaryimage","url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg","contentUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/1717647761.jpg","width":2126,"height":1417},{"@type":"BreadcrumbList","@id":"https:\/\/rotario.com.br\/site\/abertura-do-junho-verde-acontece-na-praca-do-bar-do-coco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/rotario.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Abertura do Junho Verde acontece na Pra\u00e7a do Bar do Coco"}]},{"@type":"WebSite","@id":"https:\/\/rotario.com.br\/site\/#website","url":"https:\/\/rotario.com.br\/site\/","name":"Rota Rio","description":"Aqui, o Rio de Janeiro \u00e9 a pauta!","publisher":{"@id":"https:\/\/rotario.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rotario.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/rotario.com.br\/site\/#organization","name":"Rota Rio","url":"https:\/\/rotario.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png","contentUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png","width":2048,"height":654,"caption":"Rota Rio"},"image":{"@id":"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7","name":"Galv\u00e3o","url":"https:\/\/rotario.com.br\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts\/16580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/comments?post=16580"}],"version-history":[{"count":0,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts\/16580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/media\/16581"}],"wp:attachment":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/media?parent=16580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/categories?post=16580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/tags?post=16580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}