{"id":16583,"date":"2024-06-06T16:43:09","date_gmt":"2024-06-06T19:43:09","guid":{"rendered":"https:\/\/rotario.com.br\/site\/?p=16583"},"modified":"2024-06-06T16:43:11","modified_gmt":"2024-06-06T19:43:11","slug":"campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude","status":"publish","type":"post","link":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/","title":{"rendered":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong><em>Com o tema \u201cDemocracia, Trabalho e Educa\u00e7\u00e3o na Sa\u00fade para o Desenvolvimento: Gente que Faz o SUS Acontecer\u201d, evento contou com a participa\u00e7\u00e3o de 40 delegados da Regi\u00e3o Norte Fluminense<\/em><\/strong><\/p>\n\n\n\n<p>Campos sediou, nesta quinta-feira (6), a etapa regional da 2\u00aa Confer\u00eancia Estadual de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade \u2013 2\u00aa CEGTES-RJ. Com o tema \u201cDemocracia, Trabalho e Educa\u00e7\u00e3o na Sa\u00fade para o Desenvolvimento: Gente que Faz o SUS Acontecer\u201d, o encontro aconteceu no audit\u00f3rio do Conselho Municipal de Sa\u00fade, que funciona da sede da Secretaria Municipal de Sa\u00fade (SMS), at\u00e9 as 16h, com a presen\u00e7a de 40 delegados representantes dos oitos munic\u00edpios que abrange a Regi\u00e3o Norte Fluminense, distribu\u00eddos nas categorias de usu\u00e1rio SUS, prestadores de servi\u00e7os e governo.<\/p>\n\n\n\n<p>A confer\u00eancia foi aberta pelo secret\u00e1rio municipal de Sa\u00fade e presidente do Conselho Municipal de Sa\u00fade de Campos, Paulo Hirano, ao lado do conselheiro estadual Wagner Gomes Bezerra, que representou a presidente do Conselho Estadual de Sa\u00fade, Dani Moretti. Tamb\u00e9m integraram a mesa a coordenadora da etapa regional e conselheira municipal Ant\u00f4nia Rodrigues Correa, a conselheira municipal e relatora geral, Danielle Nascimento Guimar\u00e3es, e o palestrante Lidston Pereira da Silva, que \u00e9 psic\u00f3logo, conselheiro estadual e representante dos profissionais de sa\u00fade.<\/p>\n\n\n\n<p>O principal objetivo da confer\u00eancia \u00e9 debater sobre a valoriza\u00e7\u00e3o profissional, equidade no acesso aos servi\u00e7os de sa\u00fade e formula\u00e7\u00e3o de pol\u00edticas duradouras na \u00e1rea, al\u00e9m de sintetizar as mais de 60 propostas extra\u00eddas das etapas municipais que aconteceram em maio para, no m\u00e1ximo 30. As propostas ser\u00e3o encaminhadas, posteriormente, para a 2\u00aa Confer\u00eancia Estadual, prevista para acontecer nos dias 13, 14 e 15 de julho. Elas foram trabalhadas dentro de tr\u00eas eixos tem\u00e1ticos: democracia, controle social e equidade na gest\u00e3o participativa do trabalho e da educa\u00e7\u00e3o em sa\u00fade; Trabalho digno, decente, seguro, humanizado, econ\u00f4mico e democr\u00e1tico no SUS: uma agenda estrat\u00e9gica para o futuro do Brasil; Educa\u00e7\u00e3o para o desenvolvimento do trabalho na produ\u00e7\u00e3o da sa\u00fade e do cuidado das pessoas que fazem o SUS acontecer: a sa\u00fade da democracia para a democracia da sa\u00fade.<\/p>\n\n\n\n<p>Ao se pronunciar aos presentes, Paulo Hirano tra\u00e7ou v\u00e1rias considera\u00e7\u00f5es sobre a quest\u00e3o da Gest\u00e3o do Trabalho e da Educa\u00e7\u00e3o em Sa\u00fade, a qual considera de uma complexidade inimagin\u00e1vel e gigantismo incalcul\u00e1vel. \u201cS\u00e3o dois eixos que devem ser bastante aprofundados. Nossos conselheiros j\u00e1 realizaram as etapas municipais, j\u00e1 tiramos algumas sugest\u00f5es e diretrizes que ser\u00e3o discutidas ao longo do dia, e devemos retirar desta etapa regional ideias, proposi\u00e7\u00f5es e diretrizes que possam enriquecer nossa Confer\u00eancia Estadual de forma que isso possa ir subindo de modo que possamos interferir nesse mundo gigantesco que \u00e9 o mundo do trabalho, principalmente na sa\u00fade\u201d, disse o secret\u00e1rio Hirano, que acredita que a educa\u00e7\u00e3o continuada \u00e9 fundamental para proporcionar sa\u00fade de qualidade.<\/p>\n\n\n\n<p>\u201cNossa representa\u00e7\u00e3o como trabalhador sempre nos faz pensar no tema desses tr\u00eas eixos de uma maneira muito promissora. Fazemos coro ao secret\u00e1rio na sua men\u00e7\u00e3o, seu desejo de trazer o melhor, de fazer com que nesse momento n\u00f3s possamos estar aqui colidindo da melhor maneira, com a maior boa vontade, com atitude sempre progressista, construtiva para trazer o que h\u00e1 de melhor em termo de gest\u00e3o, de participa\u00e7\u00e3o do controle social e de educa\u00e7\u00e3o. N\u00f3s temos um desejo de que essa confer\u00eancia possa acontecer de maneira uniforme, de forma que vai trazer o melhor \u00e0 sa\u00fade do munic\u00edpio e do estado\u201d, disse Wagner Gomes.<\/p>\n\n\n\n<p>O palestrante Lidston proporcionou uma reflex\u00e3o sobre a gest\u00e3o do trabalho e a educa\u00e7\u00e3o na sa\u00fade, fomentando as propostas que ser\u00e3o encaminhadas para a pr\u00f3xima etapa. \u201cEstamos num momento muito importante porque s\u00e3o as delibera\u00e7\u00f5es que s\u00e3o constru\u00eddas aqui, as delibera\u00e7\u00f5es e propostas que vieram dos munic\u00edpios, que v\u00e3o falar muito da Regi\u00e3o Norte, v\u00e3o dizer o que \u00e9 necess\u00e1rio a gente pensar, articular e fazer para que a gest\u00e3o do trabalho e educa\u00e7\u00e3o na sa\u00fade na regi\u00e3o e nos munic\u00edpios que a comp\u00f5em, tenham condi\u00e7\u00f5es de se qualificar. E essa qualifica\u00e7\u00e3o tem um grande objetivo, que \u00e9 qualificar o servi\u00e7o prestado \u00e0 popula\u00e7\u00e3o\u201d, disse.<\/p>\n\n\n\n<p>\u00c9 tamb\u00e9m nessa etapa que s\u00e3o eleitos os delegados que ir\u00e3o representar a regi\u00e3o Norte Fluminense na etapa estadual 2\u00aa Confer\u00eancia, como explica o conselheiro municipal de sa\u00fade de Campos, Jo\u00e3o Manoel Rangel. \u201cSair\u00e3o 20 delegados para a etapa estadual. L\u00e1 tamb\u00e9m haver\u00e1 uma elei\u00e7\u00e3o das propostas e de quatro delegados que seguem para etapa nacional\u201d, disse, acrescentando que a principal proposta \u00e9 a valoriza\u00e7\u00e3o do servidor em sa\u00fade, seja ele, motorista, t\u00e9cnico em enfermagem, enfermeiro, pessoal de apoio ou m\u00e9dico.<\/p>\n\n\n\n<p>\u201cA proposta \u00e9 o reconhecimento dos prestadores de servi\u00e7os, sejam eles p\u00fablicos ou privados, para que possa ter uma valoriza\u00e7\u00e3o aos usu\u00e1rios que automaticamente promover\u00e1 a valoriza\u00e7\u00e3o do SUS. O SUS quer permanecer como o grande prestador de servi\u00e7o \u00e0 popula\u00e7\u00e3o e, nisso, a gente precisa de ter uma educa\u00e7\u00e3o continuada desde a ponta que \u00e9 a UBS onde recebe o paciente at\u00e9 aqueles que est\u00e3o dentro de um centro cir\u00fargico ou UTI\u201d, completou.<\/p>\n\n\n\n<p>A Regi\u00e3o Norte Fluminense abrange os munic\u00edpios de Campos, S\u00e3o Jo\u00e3o da Barra, S\u00e3o Francisco de Itabapoana, S\u00e3o Fid\u00e9lis, Maca\u00e9, Carapebus, Quissam\u00e3 e Concei\u00e7\u00e3o de Macabu. Todos est\u00e3o representados na etapa regional da 2\u00aa CEGTES-RJ.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o tema \u201cDemocracia, Trabalho e Educa\u00e7\u00e3o na Sa\u00fade para o Desenvolvimento: Gente que Faz o SUS Acontecer\u201d, evento contou com a participa\u00e7\u00e3o de 40 delegados da Regi\u00e3o Norte Fluminense Campos sediou, nesta quinta-feira (6), a etapa regional da 2\u00aa Confer\u00eancia Estadual de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade \u2013 2\u00aa CEGTES-RJ. Com o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16584,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,225],"tags":[],"class_list":["post-16583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campos","category-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio\" \/>\n<meta property=\"og:description\" content=\"Com o tema \u201cDemocracia, Trabalho e Educa\u00e7\u00e3o na Sa\u00fade para o Desenvolvimento: Gente que Faz o SUS Acontecer\u201d, evento contou com a participa\u00e7\u00e3o de 40 delegados da Regi\u00e3o Norte Fluminense Campos sediou, nesta quinta-feira (6), a etapa regional da 2\u00aa Confer\u00eancia Estadual de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade \u2013 2\u00aa CEGTES-RJ. Com o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Rota Rio\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T19:43:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-06T19:43:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Galv\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Galv\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\"},\"author\":{\"name\":\"Galv\u00e3o\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7\"},\"headline\":\"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade\",\"datePublished\":\"2024-06-06T19:43:09+00:00\",\"dateModified\":\"2024-06-06T19:43:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\"},\"wordCount\":985,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg\",\"articleSection\":[\"Campos\",\"Destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\",\"url\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\",\"name\":\"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio\",\"isPartOf\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg\",\"datePublished\":\"2024-06-06T19:43:09+00:00\",\"dateModified\":\"2024-06-06T19:43:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage\",\"url\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg\",\"contentUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/rotario.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rotario.com.br\/site\/#website\",\"url\":\"https:\/\/rotario.com.br\/site\/\",\"name\":\"Rota Rio\",\"description\":\"Aqui, o Rio de Janeiro \u00e9 a pauta!\",\"publisher\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rotario.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rotario.com.br\/site\/#organization\",\"name\":\"Rota Rio\",\"url\":\"https:\/\/rotario.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png\",\"contentUrl\":\"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png\",\"width\":2048,\"height\":654,\"caption\":\"Rota Rio\"},\"image\":{\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7\",\"name\":\"Galv\u00e3o\",\"url\":\"https:\/\/rotario.com.br\/site\/author\/daniel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/","og_locale":"pt_BR","og_type":"article","og_title":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio","og_description":"Com o tema \u201cDemocracia, Trabalho e Educa\u00e7\u00e3o na Sa\u00fade para o Desenvolvimento: Gente que Faz o SUS Acontecer\u201d, evento contou com a participa\u00e7\u00e3o de 40 delegados da Regi\u00e3o Norte Fluminense Campos sediou, nesta quinta-feira (6), a etapa regional da 2\u00aa Confer\u00eancia Estadual de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade \u2013 2\u00aa CEGTES-RJ. Com o [&hellip;]","og_url":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/","og_site_name":"Rota Rio","article_published_time":"2024-06-06T19:43:09+00:00","article_modified_time":"2024-06-06T19:43:11+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg","type":"image\/jpeg"}],"author":"Galv\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Galv\u00e3o","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#article","isPartOf":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/"},"author":{"name":"Galv\u00e3o","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7"},"headline":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade","datePublished":"2024-06-06T19:43:09+00:00","dateModified":"2024-06-06T19:43:11+00:00","mainEntityOfPage":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/"},"wordCount":985,"commentCount":0,"publisher":{"@id":"https:\/\/rotario.com.br\/site\/#organization"},"image":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg","articleSection":["Campos","Destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/","url":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/","name":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade - Rota Rio","isPartOf":{"@id":"https:\/\/rotario.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage"},"image":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage"},"thumbnailUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg","datePublished":"2024-06-06T19:43:09+00:00","dateModified":"2024-06-06T19:43:11+00:00","breadcrumb":{"@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#primaryimage","url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg","contentUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2024\/06\/with-228218.jpeg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/rotario.com.br\/site\/campos-sedia-etapa-da-conferencia-de-gestao-do-trabalho-e-educacao-na-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/rotario.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Campos sedia etapa da Confer\u00eancia de Gest\u00e3o do Trabalho e Educa\u00e7\u00e3o na Sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/rotario.com.br\/site\/#website","url":"https:\/\/rotario.com.br\/site\/","name":"Rota Rio","description":"Aqui, o Rio de Janeiro \u00e9 a pauta!","publisher":{"@id":"https:\/\/rotario.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rotario.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/rotario.com.br\/site\/#organization","name":"Rota Rio","url":"https:\/\/rotario.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png","contentUrl":"https:\/\/rotario.com.br\/site\/wp-content\/uploads\/2022\/04\/cropped-ROTARIO-LOGO-Prancheta-1-1-2048x654-1.png","width":2048,"height":654,"caption":"Rota Rio"},"image":{"@id":"https:\/\/rotario.com.br\/site\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rotario.com.br\/site\/#\/schema\/person\/fd89bbbf4136f7e8a21e0dd67b8a66c7","name":"Galv\u00e3o","url":"https:\/\/rotario.com.br\/site\/author\/daniel\/"}]}},"_links":{"self":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts\/16583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/comments?post=16583"}],"version-history":[{"count":0,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/posts\/16583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/media\/16584"}],"wp:attachment":[{"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/media?parent=16583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/categories?post=16583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotario.com.br\/site\/wp-json\/wp\/v2\/tags?post=16583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}